{"id":8610,"date":"2019-05-25T07:31:02","date_gmt":"2019-05-25T05:31:02","guid":{"rendered":"https:\/\/www.cbd-achat.ch\/produit\/evaporateur-a-soufre-hotbox-sulfume-2\/"},"modified":"2019-05-25T07:31:02","modified_gmt":"2019-05-25T05:31:02","slug":"evaporateur-a-soufre-hotbox-sulfume-2","status":"publish","type":"product","link":"https:\/\/www.cbd-achat.ch\/es\/produit\/evaporateur-a-soufre-hotbox-sulfume-2\/","title":{"rendered":"Evaporateur \u00e0 soufre HOTBOX Sulfume"},"content":{"rendered":"<\/p>\n<p>Evaporateur \u00e0 soufre HOTBOX Sulfume<\/p>\n<p>L&#8217;\u00e9vaporateur de soufre le plus s\u00fbr du march\u00e9<\/p>\n<p>  La livraison comprend 500gr de soufre.<\/p>\n<p>  Prot\u00e8ge les plantes des maladies fongiques. Emp\u00eache \u00e9galement la propagation des ravageurs. L&#8217;\u00e9vaporateur de soufre Sulfume Hotbox a plac\u00e9 la barre si haut que le mot &#8220;sulfume&#8221;\u00a0est devenu un \u00e9ponyme pour tous les \u00e9vaporateurs de soufre. Mais ne vous m\u00e9prenez pas, tous les vaporisateurs de soufre ne sont pas ceux de Hotbox Sulfume.<\/p>\n<p>Pas de surchauffe, pas d&#8217;oxydes nocifs &#8211; SEUL le soufre pur est lib\u00e9r\u00e9.<br \/>  L&#8217;\u00e9l\u00e9ment de commande emp\u00eache le soufre de s&#8217;enflammer &#8211; pas de risque d&#8217;incendie<br \/>  Consommation d&#8217;\u00e9nergie inf\u00e9rieure \u00e0 celle de tous les autres \u00e9vaporateurs disponibles<br \/>  Fonctionnement sans perte de puissance avec toute forme d&#8217;alimentation \u00e9lectrique de 110 V \u00e0 250 V possible<br \/>  Hotbox Sulfume est l&#8217;\u00e9vaporateur de soufre \u00e0 temp\u00e9rature contr\u00f4l\u00e9e qui est id\u00e9al pour contr\u00f4ler le botrytis, la moisissure, etc.<\/p>\n<p>Hotbox Sulfume est le seul \u00e9vaporateur de soufre autor\u00e9gulateur qui assure une \u00e9vaporation efficace du soufre sans production d&#8217;autres compos\u00e9s. Cela permet un meilleur contr\u00f4le de la maladie qu&#8217;auparavant.<\/p>\n<p>BASE<br \/>  La coque de l&#8217;insert de forme r\u00e9guli\u00e8re, plac\u00e9e exactement au milieu du cylindre de parfum, assure la distribution gr\u00e2ce \u00e0 l&#8217;effet d&#8217;entonnoir naturel. Un \u00e9vaporateur de soufre suffit pour une surface de 100m\u00b2 (10\u00d710m). Cela signifie que 100-200 sulfumes par hectare sont n\u00e9cessaires.<\/p>\n<p>SHELL D&#8217;APPLICATION<br \/>  La coque de l&#8217;insert est en aluminium et a \u00e9t\u00e9 sp\u00e9cialement d\u00e9velopp\u00e9e pour l&#8217;absorption du soufre. Le bac en aluminium est fourni et ne doit \u00eatre utilis\u00e9 que pour l&#8217;\u00e9vaporation du soufre.<\/p>\n<p>ALUMINIUM<br \/>  La plaque chauffante autor\u00e9gulatrice est en aluminium de haute qualit\u00e9. Ceci garantit une longue dur\u00e9e de vie.<\/p>\n<p>CONSOMMATION<br \/>  \u00c9conomisez de l&#8217;argent avec Sulfume. Apr\u00e8s un temps de d\u00e9marrage de moins d&#8217;une seconde, l&#8217;appareil fonctionne \u00e0 100 watts jusqu&#8217;\u00e0 ce que la temp\u00e9rature souhait\u00e9e soit atteinte. Pour maintenir cette temp\u00e9rature, l&#8217;appareil n\u00e9cessite moins de 50 watts. L&#8217;autor\u00e9gulation est bas\u00e9e sur les derni\u00e8res technologies et ne fonctionne pas comme les thermostats traditionnels. Par cons\u00e9quent, la consommation ne change que tr\u00e8s lentement avec les changements de temp\u00e9rature.<\/p>\n<p>SEULEMENT S&#8217;\u00c9VAPORER &#8211; NE PAS BR\u00dbLER<br \/>  Hotbox Sulfume est le seul \u00e9vaporateur de soufre qui garantit qu&#8217;aucun soufre ne peut br\u00fbler. Hotbox veille \u00e0 ce que la r\u00e9gulation de la temp\u00e9rature fonctionne avec pr\u00e9cision, de sorte que le risque de br\u00fblure ou d&#8217;excr\u00e9tion de produits organiques ind\u00e9sirables puisse \u00eatre exclu.<\/p>\n<p>R\u00c8GLEMENT<br \/>  La plaque chauffante dans le sulfure est automatiquement r\u00e9gl\u00e9e \u00e0 la temp\u00e9rature de consigne. La temp\u00e9rature est maintenue constante. Vous ne trouverez jamais une Hotbox Sulfume au-dessus ou en dessous de la temp\u00e9rature r\u00e9gl\u00e9e.<\/p>\n<p>ACIER INOXYDABLE<br \/>  Le bo\u00eetier de l&#8217;\u00e9vaporateur de soufre Sulfume est fabriqu\u00e9 en acier inoxydable de haute qualit\u00e9, de sorte que l&#8217;appareil a \u00e9t\u00e9 con\u00e7u pour une longue dur\u00e9e de vie. Gr\u00e2ce \u00e0 la plaque chauffante autor\u00e9gulatrice et \u00e0 l&#8217;utilisation d&#8217;acier inoxydable, le bo\u00eetier peut \u00e9galement \u00eatre touch\u00e9 sans probl\u00e8me pendant l&#8217;utilisation, car il ne chauffe pas. C&#8217;est la s\u00e9curit\u00e9 sur le lieu de travail.<\/p>\n<p>IND\u00c9PENDANCE DE TENSION<br \/>  Hotbox Sulfume est vraiment ind\u00e9pendant. M\u00eame en cas de fortes fluctuations de tension, Sulfume est toujours maintenu \u00e0 une temp\u00e9rature constante.<\/p>\n<p>Nous garantissons que la consommation reste toujours constante. Hotbox Sulfume est le seul \u00e9vaporateur de soufre qui ma\u00eetrise ce mode de fonctionnement. Si la tension chute m\u00eame \u00e0 200 ou 180 volts, cela n&#8217;affecte pas la temp\u00e9rature de l&#8217;appareil.<\/p>\n<p>Sp\u00e9cifications techniques<\/p>\n<p>Rendement : 80 &#8211; 100m\u00b2 (100 &#8211; 200 pi\u00e8ces par hectare)<br \/>  Tension : 100 Volt \u00e0 240 Volt (ind\u00e9pendant de la tension)<br \/>  Consommation : 45 watts (120 watts) 120 watts pendant la phase de d\u00e9marrage. R\u00e9duit \u00e0 45 watts apr\u00e8s 5 minutes.<br \/>  Taille : 13cm de diam\u00e8tre, 18cm de hauteur<\/p>\n<p>Livr\u00e9 avec une fiche Schuko.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evaporateur \u00e0 soufre HOTBOX Sulfume L&#8217;\u00e9vaporateur de soufre le plus s\u00fbr du march\u00e9 La livraison comprend 500gr de soufre. Prot\u00e8ge les plantes des maladies fongiques. Emp\u00eache \u00e9galement la propagation des ravageurs. L&#8217;\u00e9vaporateur de soufre Sulfume Hotbox a plac\u00e9 la barre si haut que le mot &#8220;sulfume&#8221;\u00a0est devenu un \u00e9ponyme pour [&hellip;]<\/p>\n","protected":false},"featured_media":8608,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[395],"product_tag":[533,531,526,528,522,523,525,524,532,521,534,527,529,530],"_links":{"self":[{"href":"https:\/\/www.cbd-achat.ch\/es\/wp-json\/wp\/v2\/product\/8610"}],"collection":[{"href":"https:\/\/www.cbd-achat.ch\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cbd-achat.ch\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cbd-achat.ch\/es\/wp-json\/wp\/v2\/comments?post=8610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cbd-achat.ch\/es\/wp-json\/wp\/v2\/media\/8608"}],"wp:attachment":[{"href":"https:\/\/www.cbd-achat.ch\/es\/wp-json\/wp\/v2\/media?parent=8610"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cbd-achat.ch\/es\/wp-json\/wp\/v2\/product_cat?post=8610"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cbd-achat.ch\/es\/wp-json\/wp\/v2\/product_tag?post=8610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}